{"id":4426,"date":"2022-07-08T23:19:03","date_gmt":"2022-07-08T23:19:03","guid":{"rendered":"https:\/\/drmauricioleon.net\/portal\/?p=4426"},"modified":"2022-07-08T23:19:05","modified_gmt":"2022-07-08T23:19:05","slug":"definiciones-relacionadas-al-cancer","status":"publish","type":"post","link":"https:\/\/drmauricioleon.net\/portal\/2022\/07\/08\/definiciones-relacionadas-al-cancer\/","title":{"rendered":"Definiciones relacionadas al c\u00e1ncer"},"content":{"rendered":"<p><strong>C\u00e1ncer.-<\/strong> Es un conjunto de enfermedades caracterizadas por la alteraci\u00f3n del componente gen\u00e9tico de las c\u00e9lulas que adquieren caracter\u00edsticas de malignidad, como reproducci\u00f3n acelerada, inhibici\u00f3n de los mecanismos de regulaci\u00f3n, muerte celular y angiogenesis.<\/p>\n<p><strong>Factores de riesgo.-<\/strong> Es cualquier rasgo, situaci\u00f3n o caracter\u00edstica que presenta una persona que aumenta su probabilidad de sufrir una enfermedad o lesi\u00f3n.<\/p>\n<p><strong>Consejer\u00eda preventiva.-<\/strong> Es el proceso metodol\u00f3gico mediante el cual el profesional de salud brinda informaci\u00f3n preventiva a la persona sana o aparentemente sana.<\/p>\n<p><strong>Prevenci\u00f3n primaria.-<\/strong> Son todas las acciones que se realizan para disminuir el riesgo de desarrollar la enfermedad. Se realizan en la etapa pre patog\u00e9nico en el cual el sujeto est\u00e1 expuesto a factores de riesgo o agentes causales de la enfermedad.<\/p>\n<p><strong>Prevenci\u00f3n secundaria.-<\/strong> Son todas las acciones, pruebas y\/o ex\u00e1menes que se realiza una\u00a0persona para detectar y diagnosticar tempranamente una enfermedad.<\/p>\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>C\u00e1ncer.- Es un conjunto de enfermedades caracterizadas por la alteraci\u00f3n del componente gen\u00e9tico de las c\u00e9lulas que adquieren caracter\u00edsticas de malignidad, como reproducci\u00f3n acelerada, inhibici\u00f3n de los mecanismos de regulaci\u00f3n, muerte celular y angiogenesis. Factores de riesgo.- Es cualquier rasgo, situaci\u00f3n o caracter\u00edstica que presenta una persona que aumenta su probabilidad de sufrir una enfermedad [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":4427,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[57],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Definiciones relacionadas al c\u00e1ncer - %<\/title>\n<meta name=\"description\" content=\"Definiciones importantes relacionadas al c\u00e1ncer. Conceptos b\u00e1sicos en el manejo de esta enfermedad.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/drmauricioleon.net\/portal\/2022\/07\/08\/definiciones-relacionadas-al-cancer\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Definiciones relacionadas al c\u00e1ncer - %\" \/>\n<meta property=\"og:description\" content=\"Definiciones importantes relacionadas al c\u00e1ncer. Conceptos b\u00e1sicos en el manejo de esta enfermedad.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/drmauricioleon.net\/portal\/2022\/07\/08\/definiciones-relacionadas-al-cancer\/\" \/>\n<meta property=\"og:site_name\" content=\"Dr Mauricio Le\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Dr.mauricioleon\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-08T23:19:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-08T23:19:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/drmauricioleon.net\/portal\/wp-content\/uploads\/2022\/07\/consejeria.png\" \/>\n\t<meta property=\"og:image:width\" content=\"810\" \/>\n\t<meta property=\"og:image:height\" content=\"536\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@drleonmauricio\" \/>\n<meta name=\"twitter:site\" content=\"@drleonmauricio\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mauricio Le\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/drmauricioleon.net\/portal\/#organization\",\"name\":\"Dr. Mauricio Le\u00f3n\",\"url\":\"https:\/\/drmauricioleon.net\/portal\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/Dr.mauricioleon\",\"https:\/\/www.linkedin.com\/in\/mauricio-le\u00f3n-rivera-ab525598\",\"http:\/\/www.youtube.com\/user\/centrodetector\",\"https:\/\/twitter.com\/drleonmauricio\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/drmauricioleon.net\/portal\/#logo\",\"inLanguage\":\"es-PE\",\"url\":\"https:\/\/drmauricioleon.net\/portal\/wp-content\/uploads\/2020\/01\/logo-drml-e1586281768776.png\",\"contentUrl\":\"https:\/\/drmauricioleon.net\/portal\/wp-content\/uploads\/2020\/01\/logo-drml-e1586281768776.png\",\"width\":220,\"height\":72,\"caption\":\"Dr. Mauricio Le\u00f3n\"},\"image\":{\"@id\":\"https:\/\/drmauricioleon.net\/portal\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/drmauricioleon.net\/portal\/#website\",\"url\":\"https:\/\/drmauricioleon.net\/portal\/\",\"name\":\"Dr Mauricio Le\u00f3n\",\"description\":\"Cirujano general y onc\u00f3logo y sub especialista en tumores de Mamas, Tejidos Blandos y Piel. Es m\u00e9dico staff de la Cl\u00ednica Ricardo Palma y de Oncosalud.\",\"publisher\":{\"@id\":\"https:\/\/drmauricioleon.net\/portal\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/drmauricioleon.net\/portal\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-PE\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/drmauricioleon.net\/portal\/2022\/07\/08\/definiciones-relacionadas-al-cancer\/#primaryimage\",\"inLanguage\":\"es-PE\",\"url\":\"https:\/\/drmauricioleon.net\/portal\/wp-content\/uploads\/2022\/07\/consejeria.png\",\"contentUrl\":\"https:\/\/drmauricioleon.net\/portal\/wp-content\/uploads\/2022\/07\/consejeria.png\",\"width\":810,\"height\":536},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/drmauricioleon.net\/portal\/2022\/07\/08\/definiciones-relacionadas-al-cancer\/#webpage\",\"url\":\"https:\/\/drmauricioleon.net\/portal\/2022\/07\/08\/definiciones-relacionadas-al-cancer\/\",\"name\":\"Definiciones relacionadas al c\u00e1ncer - %\",\"isPartOf\":{\"@id\":\"https:\/\/drmauricioleon.net\/portal\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/drmauricioleon.net\/portal\/2022\/07\/08\/definiciones-relacionadas-al-cancer\/#primaryimage\"},\"datePublished\":\"2022-07-08T23:19:03+00:00\",\"dateModified\":\"2022-07-08T23:19:05+00:00\",\"description\":\"Definiciones importantes relacionadas al c\u00e1ncer. Conceptos b\u00e1sicos en el manejo de esta enfermedad.\",\"breadcrumb\":{\"@id\":\"https:\/\/drmauricioleon.net\/portal\/2022\/07\/08\/definiciones-relacionadas-al-cancer\/#breadcrumb\"},\"inLanguage\":\"es-PE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/drmauricioleon.net\/portal\/2022\/07\/08\/definiciones-relacionadas-al-cancer\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/drmauricioleon.net\/portal\/2022\/07\/08\/definiciones-relacionadas-al-cancer\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/drmauricioleon.net\/portal\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Definiciones relacionadas al c\u00e1ncer\"}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/drmauricioleon.net\/portal\/2022\/07\/08\/definiciones-relacionadas-al-cancer\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/drmauricioleon.net\/portal\/2022\/07\/08\/definiciones-relacionadas-al-cancer\/#webpage\"},\"author\":{\"@id\":\"https:\/\/drmauricioleon.net\/portal\/#\/schema\/person\/b453c933295f6151407ceda3b9bf95a4\"},\"headline\":\"Definiciones relacionadas al c\u00e1ncer\",\"datePublished\":\"2022-07-08T23:19:03+00:00\",\"dateModified\":\"2022-07-08T23:19:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/drmauricioleon.net\/portal\/2022\/07\/08\/definiciones-relacionadas-al-cancer\/#webpage\"},\"wordCount\":171,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/drmauricioleon.net\/portal\/#organization\"},\"image\":{\"@id\":\"https:\/\/drmauricioleon.net\/portal\/2022\/07\/08\/definiciones-relacionadas-al-cancer\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/drmauricioleon.net\/portal\/wp-content\/uploads\/2022\/07\/consejeria.png\",\"articleSection\":[\"Informativo\"],\"inLanguage\":\"es-PE\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/drmauricioleon.net\/portal\/2022\/07\/08\/definiciones-relacionadas-al-cancer\/#respond\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/drmauricioleon.net\/portal\/#\/schema\/person\/b453c933295f6151407ceda3b9bf95a4\",\"name\":\"Mauricio Le\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/drmauricioleon.net\/portal\/#personlogo\",\"inLanguage\":\"es-PE\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/430c938de37db4d449829c9260d5025f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/430c938de37db4d449829c9260d5025f?s=96&d=mm&r=g\",\"caption\":\"Mauricio Le\u00f3n\"},\"url\":\"https:\/\/drmauricioleon.net\/portal\/author\/bardales\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Definiciones relacionadas al c\u00e1ncer - %","description":"Definiciones importantes relacionadas al c\u00e1ncer. Conceptos b\u00e1sicos en el manejo de esta enfermedad.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/drmauricioleon.net\/portal\/2022\/07\/08\/definiciones-relacionadas-al-cancer\/","og_locale":"es_ES","og_type":"article","og_title":"Definiciones relacionadas al c\u00e1ncer - %","og_description":"Definiciones importantes relacionadas al c\u00e1ncer. Conceptos b\u00e1sicos en el manejo de esta enfermedad.","og_url":"https:\/\/drmauricioleon.net\/portal\/2022\/07\/08\/definiciones-relacionadas-al-cancer\/","og_site_name":"Dr Mauricio Le\u00f3n","article_publisher":"https:\/\/www.facebook.com\/Dr.mauricioleon","article_published_time":"2022-07-08T23:19:03+00:00","article_modified_time":"2022-07-08T23:19:05+00:00","og_image":[{"width":810,"height":536,"url":"https:\/\/drmauricioleon.net\/portal\/wp-content\/uploads\/2022\/07\/consejeria.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_creator":"@drleonmauricio","twitter_site":"@drleonmauricio","twitter_misc":{"Written by":"Mauricio Le\u00f3n","Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/drmauricioleon.net\/portal\/#organization","name":"Dr. Mauricio Le\u00f3n","url":"https:\/\/drmauricioleon.net\/portal\/","sameAs":["https:\/\/www.facebook.com\/Dr.mauricioleon","https:\/\/www.linkedin.com\/in\/mauricio-le\u00f3n-rivera-ab525598","http:\/\/www.youtube.com\/user\/centrodetector","https:\/\/twitter.com\/drleonmauricio"],"logo":{"@type":"ImageObject","@id":"https:\/\/drmauricioleon.net\/portal\/#logo","inLanguage":"es-PE","url":"https:\/\/drmauricioleon.net\/portal\/wp-content\/uploads\/2020\/01\/logo-drml-e1586281768776.png","contentUrl":"https:\/\/drmauricioleon.net\/portal\/wp-content\/uploads\/2020\/01\/logo-drml-e1586281768776.png","width":220,"height":72,"caption":"Dr. Mauricio Le\u00f3n"},"image":{"@id":"https:\/\/drmauricioleon.net\/portal\/#logo"}},{"@type":"WebSite","@id":"https:\/\/drmauricioleon.net\/portal\/#website","url":"https:\/\/drmauricioleon.net\/portal\/","name":"Dr Mauricio Le\u00f3n","description":"Cirujano general y onc\u00f3logo y sub especialista en tumores de Mamas, Tejidos Blandos y Piel. Es m\u00e9dico staff de la Cl\u00ednica Ricardo Palma y de Oncosalud.","publisher":{"@id":"https:\/\/drmauricioleon.net\/portal\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/drmauricioleon.net\/portal\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-PE"},{"@type":"ImageObject","@id":"https:\/\/drmauricioleon.net\/portal\/2022\/07\/08\/definiciones-relacionadas-al-cancer\/#primaryimage","inLanguage":"es-PE","url":"https:\/\/drmauricioleon.net\/portal\/wp-content\/uploads\/2022\/07\/consejeria.png","contentUrl":"https:\/\/drmauricioleon.net\/portal\/wp-content\/uploads\/2022\/07\/consejeria.png","width":810,"height":536},{"@type":"WebPage","@id":"https:\/\/drmauricioleon.net\/portal\/2022\/07\/08\/definiciones-relacionadas-al-cancer\/#webpage","url":"https:\/\/drmauricioleon.net\/portal\/2022\/07\/08\/definiciones-relacionadas-al-cancer\/","name":"Definiciones relacionadas al c\u00e1ncer - %","isPartOf":{"@id":"https:\/\/drmauricioleon.net\/portal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/drmauricioleon.net\/portal\/2022\/07\/08\/definiciones-relacionadas-al-cancer\/#primaryimage"},"datePublished":"2022-07-08T23:19:03+00:00","dateModified":"2022-07-08T23:19:05+00:00","description":"Definiciones importantes relacionadas al c\u00e1ncer. Conceptos b\u00e1sicos en el manejo de esta enfermedad.","breadcrumb":{"@id":"https:\/\/drmauricioleon.net\/portal\/2022\/07\/08\/definiciones-relacionadas-al-cancer\/#breadcrumb"},"inLanguage":"es-PE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/drmauricioleon.net\/portal\/2022\/07\/08\/definiciones-relacionadas-al-cancer\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/drmauricioleon.net\/portal\/2022\/07\/08\/definiciones-relacionadas-al-cancer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/drmauricioleon.net\/portal\/"},{"@type":"ListItem","position":2,"name":"Definiciones relacionadas al c\u00e1ncer"}]},{"@type":"Article","@id":"https:\/\/drmauricioleon.net\/portal\/2022\/07\/08\/definiciones-relacionadas-al-cancer\/#article","isPartOf":{"@id":"https:\/\/drmauricioleon.net\/portal\/2022\/07\/08\/definiciones-relacionadas-al-cancer\/#webpage"},"author":{"@id":"https:\/\/drmauricioleon.net\/portal\/#\/schema\/person\/b453c933295f6151407ceda3b9bf95a4"},"headline":"Definiciones relacionadas al c\u00e1ncer","datePublished":"2022-07-08T23:19:03+00:00","dateModified":"2022-07-08T23:19:05+00:00","mainEntityOfPage":{"@id":"https:\/\/drmauricioleon.net\/portal\/2022\/07\/08\/definiciones-relacionadas-al-cancer\/#webpage"},"wordCount":171,"commentCount":0,"publisher":{"@id":"https:\/\/drmauricioleon.net\/portal\/#organization"},"image":{"@id":"https:\/\/drmauricioleon.net\/portal\/2022\/07\/08\/definiciones-relacionadas-al-cancer\/#primaryimage"},"thumbnailUrl":"https:\/\/drmauricioleon.net\/portal\/wp-content\/uploads\/2022\/07\/consejeria.png","articleSection":["Informativo"],"inLanguage":"es-PE","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/drmauricioleon.net\/portal\/2022\/07\/08\/definiciones-relacionadas-al-cancer\/#respond"]}]},{"@type":"Person","@id":"https:\/\/drmauricioleon.net\/portal\/#\/schema\/person\/b453c933295f6151407ceda3b9bf95a4","name":"Mauricio Le\u00f3n","image":{"@type":"ImageObject","@id":"https:\/\/drmauricioleon.net\/portal\/#personlogo","inLanguage":"es-PE","url":"https:\/\/secure.gravatar.com\/avatar\/430c938de37db4d449829c9260d5025f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/430c938de37db4d449829c9260d5025f?s=96&d=mm&r=g","caption":"Mauricio Le\u00f3n"},"url":"https:\/\/drmauricioleon.net\/portal\/author\/bardales\/"}]}},"_links":{"self":[{"href":"https:\/\/drmauricioleon.net\/portal\/wp-json\/wp\/v2\/posts\/4426"}],"collection":[{"href":"https:\/\/drmauricioleon.net\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/drmauricioleon.net\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/drmauricioleon.net\/portal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/drmauricioleon.net\/portal\/wp-json\/wp\/v2\/comments?post=4426"}],"version-history":[{"count":1,"href":"https:\/\/drmauricioleon.net\/portal\/wp-json\/wp\/v2\/posts\/4426\/revisions"}],"predecessor-version":[{"id":4428,"href":"https:\/\/drmauricioleon.net\/portal\/wp-json\/wp\/v2\/posts\/4426\/revisions\/4428"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/drmauricioleon.net\/portal\/wp-json\/wp\/v2\/media\/4427"}],"wp:attachment":[{"href":"https:\/\/drmauricioleon.net\/portal\/wp-json\/wp\/v2\/media?parent=4426"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/drmauricioleon.net\/portal\/wp-json\/wp\/v2\/categories?post=4426"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/drmauricioleon.net\/portal\/wp-json\/wp\/v2\/tags?post=4426"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}