{"id":4407,"date":"2022-07-06T22:20:44","date_gmt":"2022-07-06T22:20:44","guid":{"rendered":"https:\/\/drmauricioleon.net\/portal\/?p=4407"},"modified":"2022-07-06T22:20:46","modified_gmt":"2022-07-06T22:20:46","slug":"que-es-el-melanoma","status":"publish","type":"post","link":"https:\/\/drmauricioleon.net\/portal\/2022\/07\/06\/que-es-el-melanoma\/","title":{"rendered":"\u00bfQu\u00e9 es el melanoma?"},"content":{"rendered":"<p>El melanoma es el tipo de c\u00e1ncer cut\u00e1neo menos frecuente pero el m\u00e1s agresivo porque es capaz de generar &#8220;met\u00e1stasis&#8221; o diseminarse a otros \u00f3rganos en corto tiempo, de ah\u00ed su alta letalidad, se\u00f1al\u00f3 el Dr. Mauricio Le\u00f3n Rivera, director de la Liga Contra el C\u00e1ncer, director m\u00e9dico del Centro Detector del C\u00e1ncer y cirujano onc\u00f3logo de la Cl\u00ednica Ricardo Palma.<\/p>\n<p>El especialista mencion\u00f3 que en los varones este mal suele presentarse en la piel del tronco, cuello o espalda, y en mujeres en brazos o piernas, aunque es necesario una buena evaluaci\u00f3n porque se puede encontrar en cualquier lugar de la piel. \u201cPor ejemplo, las lesiones pigmentadas o lunares debajo de las u\u00f1as, planta de los pies o palma de las manos deben &#8220;siempre&#8221; ser evaluadas por un especialista para descartar esta neoplasia\u201d, a\u00f1adi\u00f3.<\/p>\n<p>Los principales afectados son generalmente personas mayores de 40 a\u00f1os, debido a la sobreexposici\u00f3n a la radiaci\u00f3n ultravioleta del sol, ya sea de forma constante o intermitente durante varios a\u00f1os.<\/p>\n<p><strong>Importancia de la autoexploraci\u00f3n<\/strong><\/p>\n<p>Consiste en la revisi\u00f3n de la superficie corporal cada 6 meses siguiendo siempre el mismo recorrido para no olvidar ninguna zona: cuero cabelludo, cuello, tronco, brazos, piernas, plantas de pies y palma de manos. Se debe realizar de preferencia en una habitaci\u00f3n correctamente iluminada, adem\u00e1s es necesario un espejo o la ayuda de la pareja o un familiar.<\/p>\n<p>En ese sentido, dijo que una forma f\u00e1cil de reconocer los signos del c\u00e1ncer de piel es recordar las primeras letras del abecedario.<\/p>\n<p><strong>\u201cA\u201d<\/strong> de asimetr\u00eda. Si colocas un espejo por la mitad de la lesi\u00f3n (&#8220;lunar&#8221;), ambas deben ser iguales; si esto no es as\u00ed, puede ser un signo de c\u00e1ncer.<\/p>\n<p><strong>\u201cB\u201d<\/strong> de borde. Si el borde de la lesi\u00f3n es irregular, (\u201cfestoneado\u201d), ser\u00eda otro signo de alarma.<\/p>\n<p><strong>\u201cC\u201d<\/strong> de color, normalmente los lunares benignos tienen un color homog\u00e9neo, como negro, azul o rojo, las lesiones malignas presentan varios colores.<\/p>\n<p><strong>\u201cD\u201d<\/strong> est\u00e1 relacionado al di\u00e1metro, cuando el &#8220;lunar&#8221; excede los 6 mil\u00edmetros podr\u00eda ser un c\u00e1ncer de piel.<\/p>\n<p><strong>\u201cE\u201d<\/strong> de evoluci\u00f3n. Si detectamos que una de nuestras lesiones (&#8220;lunares&#8221;) cambia, pica o se ulcera y\/o sangra puede ser que se haya malignizado.<\/p>\n<p>En caso tengas dos o m\u00e1s signos de lo anteriormente detallado, el doctor Le\u00f3n recomienda asistir inmediatamente a una consulta con un m\u00e9dico dermat\u00f3logo para la evaluaci\u00f3n adecuada y de ser necesario tambi\u00e9n una biopsia.<\/p>\n<p>Cabe mencionar, que el 23 de mayo se celebra el D\u00eda Mundial del Melanoma con el objetivo de concientizar a la poblaci\u00f3n sobre la importancia en la prevenci\u00f3n de esta terrible enfermedad.<\/p>\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El melanoma es el tipo de c\u00e1ncer cut\u00e1neo menos frecuente pero el m\u00e1s agresivo porque es capaz de generar &#8220;met\u00e1stasis&#8221; o diseminarse a otros \u00f3rganos en corto tiempo, de ah\u00ed su alta letalidad, se\u00f1al\u00f3 el Dr. Mauricio Le\u00f3n Rivera, director de la Liga Contra el C\u00e1ncer, director m\u00e9dico del Centro Detector del C\u00e1ncer y cirujano [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":4408,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[57],"tags":[196,211],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfQu\u00e9 es el melanoma? - %<\/title>\n<meta name=\"description\" content=\"El melanoma es el tipo de c\u00e1ncer cut\u00e1neo menos frecuente pero el m\u00e1s agresivo porque es capaz de generar &quot;met\u00e1stasis&quot; o diseminarse a otros \u00f3rganos en corto tiempo, de ah\u00ed su alta letalidad.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/drmauricioleon.net\/portal\/2022\/07\/06\/que-es-el-melanoma\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQu\u00e9 es el melanoma? - %\" \/>\n<meta property=\"og:description\" content=\"El melanoma es el tipo de c\u00e1ncer cut\u00e1neo menos frecuente pero el m\u00e1s agresivo porque es capaz de generar &quot;met\u00e1stasis&quot; o diseminarse a otros \u00f3rganos en corto tiempo, de ah\u00ed su alta letalidad.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/drmauricioleon.net\/portal\/2022\/07\/06\/que-es-el-melanoma\/\" \/>\n<meta property=\"og:site_name\" content=\"Dr Mauricio Le\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Dr.mauricioleon\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-06T22:20:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-06T22:20:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/drmauricioleon.net\/portal\/wp-content\/uploads\/2022\/07\/Melanoma-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"810\" \/>\n\t<meta property=\"og:image:height\" content=\"527\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@drleonmauricio\" \/>\n<meta name=\"twitter:site\" content=\"@drleonmauricio\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mauricio Le\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/drmauricioleon.net\/portal\/#organization\",\"name\":\"Dr. Mauricio Le\u00f3n\",\"url\":\"https:\/\/drmauricioleon.net\/portal\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/Dr.mauricioleon\",\"https:\/\/www.linkedin.com\/in\/mauricio-le\u00f3n-rivera-ab525598\",\"http:\/\/www.youtube.com\/user\/centrodetector\",\"https:\/\/twitter.com\/drleonmauricio\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/drmauricioleon.net\/portal\/#logo\",\"inLanguage\":\"es-PE\",\"url\":\"https:\/\/drmauricioleon.net\/portal\/wp-content\/uploads\/2020\/01\/logo-drml-e1586281768776.png\",\"contentUrl\":\"https:\/\/drmauricioleon.net\/portal\/wp-content\/uploads\/2020\/01\/logo-drml-e1586281768776.png\",\"width\":220,\"height\":72,\"caption\":\"Dr. Mauricio Le\u00f3n\"},\"image\":{\"@id\":\"https:\/\/drmauricioleon.net\/portal\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/drmauricioleon.net\/portal\/#website\",\"url\":\"https:\/\/drmauricioleon.net\/portal\/\",\"name\":\"Dr Mauricio Le\u00f3n\",\"description\":\"Cirujano general y onc\u00f3logo y sub especialista en tumores de Mamas, Tejidos Blandos y Piel. Es m\u00e9dico staff de la Cl\u00ednica Ricardo Palma y de Oncosalud.\",\"publisher\":{\"@id\":\"https:\/\/drmauricioleon.net\/portal\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/drmauricioleon.net\/portal\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-PE\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/drmauricioleon.net\/portal\/2022\/07\/06\/que-es-el-melanoma\/#primaryimage\",\"inLanguage\":\"es-PE\",\"url\":\"https:\/\/drmauricioleon.net\/portal\/wp-content\/uploads\/2022\/07\/Melanoma-2.png\",\"contentUrl\":\"https:\/\/drmauricioleon.net\/portal\/wp-content\/uploads\/2022\/07\/Melanoma-2.png\",\"width\":810,\"height\":527},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/drmauricioleon.net\/portal\/2022\/07\/06\/que-es-el-melanoma\/#webpage\",\"url\":\"https:\/\/drmauricioleon.net\/portal\/2022\/07\/06\/que-es-el-melanoma\/\",\"name\":\"\u00bfQu\u00e9 es el melanoma? - %\",\"isPartOf\":{\"@id\":\"https:\/\/drmauricioleon.net\/portal\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/drmauricioleon.net\/portal\/2022\/07\/06\/que-es-el-melanoma\/#primaryimage\"},\"datePublished\":\"2022-07-06T22:20:44+00:00\",\"dateModified\":\"2022-07-06T22:20:46+00:00\",\"description\":\"El melanoma es el tipo de c\u00e1ncer cut\u00e1neo menos frecuente pero el m\u00e1s agresivo porque es capaz de generar \\\"met\u00e1stasis\\\" o diseminarse a otros \u00f3rganos en corto tiempo, de ah\u00ed su alta letalidad.\",\"breadcrumb\":{\"@id\":\"https:\/\/drmauricioleon.net\/portal\/2022\/07\/06\/que-es-el-melanoma\/#breadcrumb\"},\"inLanguage\":\"es-PE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/drmauricioleon.net\/portal\/2022\/07\/06\/que-es-el-melanoma\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/drmauricioleon.net\/portal\/2022\/07\/06\/que-es-el-melanoma\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/drmauricioleon.net\/portal\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfQu\u00e9 es el melanoma?\"}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/drmauricioleon.net\/portal\/2022\/07\/06\/que-es-el-melanoma\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/drmauricioleon.net\/portal\/2022\/07\/06\/que-es-el-melanoma\/#webpage\"},\"author\":{\"@id\":\"https:\/\/drmauricioleon.net\/portal\/#\/schema\/person\/b453c933295f6151407ceda3b9bf95a4\"},\"headline\":\"\u00bfQu\u00e9 es el melanoma?\",\"datePublished\":\"2022-07-06T22:20:44+00:00\",\"dateModified\":\"2022-07-06T22:20:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/drmauricioleon.net\/portal\/2022\/07\/06\/que-es-el-melanoma\/#webpage\"},\"wordCount\":472,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/drmauricioleon.net\/portal\/#organization\"},\"image\":{\"@id\":\"https:\/\/drmauricioleon.net\/portal\/2022\/07\/06\/que-es-el-melanoma\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/drmauricioleon.net\/portal\/wp-content\/uploads\/2022\/07\/Melanoma-2.png\",\"keywords\":[\"c\u00e1ncer de piel\",\"melanoma\"],\"articleSection\":[\"Informativo\"],\"inLanguage\":\"es-PE\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/drmauricioleon.net\/portal\/2022\/07\/06\/que-es-el-melanoma\/#respond\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/drmauricioleon.net\/portal\/#\/schema\/person\/b453c933295f6151407ceda3b9bf95a4\",\"name\":\"Mauricio Le\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/drmauricioleon.net\/portal\/#personlogo\",\"inLanguage\":\"es-PE\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/430c938de37db4d449829c9260d5025f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/430c938de37db4d449829c9260d5025f?s=96&d=mm&r=g\",\"caption\":\"Mauricio Le\u00f3n\"},\"url\":\"https:\/\/drmauricioleon.net\/portal\/author\/bardales\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfQu\u00e9 es el melanoma? - %","description":"El melanoma es el tipo de c\u00e1ncer cut\u00e1neo menos frecuente pero el m\u00e1s agresivo porque es capaz de generar \"met\u00e1stasis\" o diseminarse a otros \u00f3rganos en corto tiempo, de ah\u00ed su alta letalidad.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/drmauricioleon.net\/portal\/2022\/07\/06\/que-es-el-melanoma\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfQu\u00e9 es el melanoma? - %","og_description":"El melanoma es el tipo de c\u00e1ncer cut\u00e1neo menos frecuente pero el m\u00e1s agresivo porque es capaz de generar \"met\u00e1stasis\" o diseminarse a otros \u00f3rganos en corto tiempo, de ah\u00ed su alta letalidad.","og_url":"https:\/\/drmauricioleon.net\/portal\/2022\/07\/06\/que-es-el-melanoma\/","og_site_name":"Dr Mauricio Le\u00f3n","article_publisher":"https:\/\/www.facebook.com\/Dr.mauricioleon","article_published_time":"2022-07-06T22:20:44+00:00","article_modified_time":"2022-07-06T22:20:46+00:00","og_image":[{"width":810,"height":527,"url":"https:\/\/drmauricioleon.net\/portal\/wp-content\/uploads\/2022\/07\/Melanoma-2.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_creator":"@drleonmauricio","twitter_site":"@drleonmauricio","twitter_misc":{"Written by":"Mauricio Le\u00f3n","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/drmauricioleon.net\/portal\/#organization","name":"Dr. Mauricio Le\u00f3n","url":"https:\/\/drmauricioleon.net\/portal\/","sameAs":["https:\/\/www.facebook.com\/Dr.mauricioleon","https:\/\/www.linkedin.com\/in\/mauricio-le\u00f3n-rivera-ab525598","http:\/\/www.youtube.com\/user\/centrodetector","https:\/\/twitter.com\/drleonmauricio"],"logo":{"@type":"ImageObject","@id":"https:\/\/drmauricioleon.net\/portal\/#logo","inLanguage":"es-PE","url":"https:\/\/drmauricioleon.net\/portal\/wp-content\/uploads\/2020\/01\/logo-drml-e1586281768776.png","contentUrl":"https:\/\/drmauricioleon.net\/portal\/wp-content\/uploads\/2020\/01\/logo-drml-e1586281768776.png","width":220,"height":72,"caption":"Dr. Mauricio Le\u00f3n"},"image":{"@id":"https:\/\/drmauricioleon.net\/portal\/#logo"}},{"@type":"WebSite","@id":"https:\/\/drmauricioleon.net\/portal\/#website","url":"https:\/\/drmauricioleon.net\/portal\/","name":"Dr Mauricio Le\u00f3n","description":"Cirujano general y onc\u00f3logo y sub especialista en tumores de Mamas, Tejidos Blandos y Piel. Es m\u00e9dico staff de la Cl\u00ednica Ricardo Palma y de Oncosalud.","publisher":{"@id":"https:\/\/drmauricioleon.net\/portal\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/drmauricioleon.net\/portal\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-PE"},{"@type":"ImageObject","@id":"https:\/\/drmauricioleon.net\/portal\/2022\/07\/06\/que-es-el-melanoma\/#primaryimage","inLanguage":"es-PE","url":"https:\/\/drmauricioleon.net\/portal\/wp-content\/uploads\/2022\/07\/Melanoma-2.png","contentUrl":"https:\/\/drmauricioleon.net\/portal\/wp-content\/uploads\/2022\/07\/Melanoma-2.png","width":810,"height":527},{"@type":"WebPage","@id":"https:\/\/drmauricioleon.net\/portal\/2022\/07\/06\/que-es-el-melanoma\/#webpage","url":"https:\/\/drmauricioleon.net\/portal\/2022\/07\/06\/que-es-el-melanoma\/","name":"\u00bfQu\u00e9 es el melanoma? - %","isPartOf":{"@id":"https:\/\/drmauricioleon.net\/portal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/drmauricioleon.net\/portal\/2022\/07\/06\/que-es-el-melanoma\/#primaryimage"},"datePublished":"2022-07-06T22:20:44+00:00","dateModified":"2022-07-06T22:20:46+00:00","description":"El melanoma es el tipo de c\u00e1ncer cut\u00e1neo menos frecuente pero el m\u00e1s agresivo porque es capaz de generar \"met\u00e1stasis\" o diseminarse a otros \u00f3rganos en corto tiempo, de ah\u00ed su alta letalidad.","breadcrumb":{"@id":"https:\/\/drmauricioleon.net\/portal\/2022\/07\/06\/que-es-el-melanoma\/#breadcrumb"},"inLanguage":"es-PE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/drmauricioleon.net\/portal\/2022\/07\/06\/que-es-el-melanoma\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/drmauricioleon.net\/portal\/2022\/07\/06\/que-es-el-melanoma\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/drmauricioleon.net\/portal\/"},{"@type":"ListItem","position":2,"name":"\u00bfQu\u00e9 es el melanoma?"}]},{"@type":"Article","@id":"https:\/\/drmauricioleon.net\/portal\/2022\/07\/06\/que-es-el-melanoma\/#article","isPartOf":{"@id":"https:\/\/drmauricioleon.net\/portal\/2022\/07\/06\/que-es-el-melanoma\/#webpage"},"author":{"@id":"https:\/\/drmauricioleon.net\/portal\/#\/schema\/person\/b453c933295f6151407ceda3b9bf95a4"},"headline":"\u00bfQu\u00e9 es el melanoma?","datePublished":"2022-07-06T22:20:44+00:00","dateModified":"2022-07-06T22:20:46+00:00","mainEntityOfPage":{"@id":"https:\/\/drmauricioleon.net\/portal\/2022\/07\/06\/que-es-el-melanoma\/#webpage"},"wordCount":472,"commentCount":0,"publisher":{"@id":"https:\/\/drmauricioleon.net\/portal\/#organization"},"image":{"@id":"https:\/\/drmauricioleon.net\/portal\/2022\/07\/06\/que-es-el-melanoma\/#primaryimage"},"thumbnailUrl":"https:\/\/drmauricioleon.net\/portal\/wp-content\/uploads\/2022\/07\/Melanoma-2.png","keywords":["c\u00e1ncer de piel","melanoma"],"articleSection":["Informativo"],"inLanguage":"es-PE","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/drmauricioleon.net\/portal\/2022\/07\/06\/que-es-el-melanoma\/#respond"]}]},{"@type":"Person","@id":"https:\/\/drmauricioleon.net\/portal\/#\/schema\/person\/b453c933295f6151407ceda3b9bf95a4","name":"Mauricio Le\u00f3n","image":{"@type":"ImageObject","@id":"https:\/\/drmauricioleon.net\/portal\/#personlogo","inLanguage":"es-PE","url":"https:\/\/secure.gravatar.com\/avatar\/430c938de37db4d449829c9260d5025f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/430c938de37db4d449829c9260d5025f?s=96&d=mm&r=g","caption":"Mauricio Le\u00f3n"},"url":"https:\/\/drmauricioleon.net\/portal\/author\/bardales\/"}]}},"_links":{"self":[{"href":"https:\/\/drmauricioleon.net\/portal\/wp-json\/wp\/v2\/posts\/4407"}],"collection":[{"href":"https:\/\/drmauricioleon.net\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/drmauricioleon.net\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/drmauricioleon.net\/portal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/drmauricioleon.net\/portal\/wp-json\/wp\/v2\/comments?post=4407"}],"version-history":[{"count":1,"href":"https:\/\/drmauricioleon.net\/portal\/wp-json\/wp\/v2\/posts\/4407\/revisions"}],"predecessor-version":[{"id":4409,"href":"https:\/\/drmauricioleon.net\/portal\/wp-json\/wp\/v2\/posts\/4407\/revisions\/4409"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/drmauricioleon.net\/portal\/wp-json\/wp\/v2\/media\/4408"}],"wp:attachment":[{"href":"https:\/\/drmauricioleon.net\/portal\/wp-json\/wp\/v2\/media?parent=4407"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/drmauricioleon.net\/portal\/wp-json\/wp\/v2\/categories?post=4407"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/drmauricioleon.net\/portal\/wp-json\/wp\/v2\/tags?post=4407"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}