{"id":4060,"date":"2017-04-20T19:52:00","date_gmt":"2017-04-20T19:52:00","guid":{"rendered":"https:\/\/drmauricioleon.net\/portal\/?p=4060"},"modified":"2021-09-06T19:56:24","modified_gmt":"2021-09-06T19:56:24","slug":"envases-de-plastico-y-o-tecnopor-podrian-originar-cancer","status":"publish","type":"post","link":"https:\/\/drmauricioleon.net\/portal\/2017\/04\/20\/envases-de-plastico-y-o-tecnopor-podrian-originar-cancer\/","title":{"rendered":"Envases de pl\u00e1stico y\/o tecnopor podr\u00edan originar c\u00e1ncer"},"content":{"rendered":"<p><strong>De acuerdo a investigaciones de los \u00faltimos 50 a\u00f1os a nivel mundial.<\/strong><\/p>\n<p>Los envases de pl\u00e1stico y\/o tecnopor utilizados para servir o almacenar las comidas podr\u00edan originar c\u00e1ncer si es que se someten a altas temperaturas, de acuerdo a investigaciones a nivel mundial de los \u00faltimos 50 a\u00f1os, indic\u00f3 el Dr. Mauricio Le\u00f3n Rivera, director m\u00e9dico del Centro Detector del C\u00e1ncer y cirujano onc\u00f3logo de la Cl\u00ednica Ricardo Palma.<\/p>\n<p>En el caso de los pl\u00e1sticos existes dos sustancias qu\u00edmicas que resaltan por su toxicidad siendo da\u00f1inas para la salud humana, son el bisfenol A (BPA) y los ptalatos, que encuentran en miles de objetos hechos de ese material.<\/p>\n<p>La exposici\u00f3n a esos objetos en la vida moderna es tal, que incluso la mayor\u00eda de ni\u00f1os tiene esas sustancias en la sangre, debido principalmente a los juguetes, biberones y botellas de pl\u00e1stico.<\/p>\n<p>\u201cSe estiman que m\u00e1s de 8 millones de toneladas de pl\u00e1stico van a parar al oc\u00e9ano anualmente causando gran contaminaci\u00f3n, adem\u00e1s de problemas en la red de desag\u00fces como ocurri\u00f3 durante una inundaci\u00f3n en Bangladesh, por lo que en el 2002 prohibieron su uso. China, Kenia, Ruanda y recientemente Francia han prohibido la distribuci\u00f3n de bolsas de pl\u00e1stico en los supermercados, as\u00ed como platos y vasos de pl\u00e1stico desechables, reemplaz\u00e1ndolos por otros que contienen material biol\u00f3gico, agreg\u00f3 el especialista.<\/p>\n<p>En cuanto al tecnopor o lo que es lo mismo, el pol\u00edmero de estireno \u201cpoliestireno\u201d, que es un derivado del petr\u00f3leo, es considerado un carcin\u00f3geno en animales y probablemente en humanos y que al interactuar con el calor, libera f\u00e1cilmente un componente llamado estireno, causando da\u00f1os en las c\u00e9lulas, aumentando el riesgo a desarrollar distintos tipos de c\u00e1ncer como leucemia, c\u00e1ncer cerebral y\/o de m\u00e9dula \u00f3sea principalmente.<\/p>\n<p>Adem\u00e1s, tiene impacto sobre el medio ambiente ya que el poliestireno tarda m\u00e1s de 500 a\u00f1os en degradarse y lo que es peor, no se puede reciclar a gran escala, infectando mares, r\u00edos y tierras, descomponi\u00e9ndose lentamente en su mon\u00f3mero llamado estireno, el cual pasa al aire que respiramos, v\u00eda principal de contaminaci\u00f3n humana, a la tierra y\/o a las plantas que consumimos contaminando todo a nuestro alrededor.<\/p>\n<p>En la actualidad, la Organizaci\u00f3n Mundial de la Salud (OMS), dentro de su listado de grupos de riesgo que clasifican a los elementos cancer\u00edgenos, clasifica al poliestireno dentro del grupo 3, habiendo ya demostrado el aumento del riesgo de c\u00e1ncer en animales, pero aun no fehacientemente en seres humanos.<\/p>\n<p>Cabe mencionar, que recientemente, Nueva York se ha unido a otras 70 ciudades como Washington DC, Portland, Seattle o pa\u00edses como Taiw\u00e1n, donde ya est\u00e1n prohibidos los envases de poliestireno com\u00fanmente conocidos como \u201ctecnopor\u201d para su uso en comidas y\/o bebidas, incluso algunas cadenas de comida r\u00e1pida ya retiraron los envases de tecnopor en todos sus locales reemplaz\u00e1ndolos por envases de papel y envases de polipropileno, material que es m\u00e1s f\u00e1cilmente reciclable pero m\u00e1s costoso.<\/p>\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>De acuerdo a investigaciones de los \u00faltimos 50 a\u00f1os a nivel mundial. Los envases de pl\u00e1stico y\/o tecnopor utilizados para servir o almacenar las comidas podr\u00edan originar c\u00e1ncer si es que se someten a altas temperaturas, de acuerdo a investigaciones a nivel mundial de los \u00faltimos 50 a\u00f1os, indic\u00f3 el Dr. Mauricio Le\u00f3n Rivera, director [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":4061,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[57],"tags":[455,382,456],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Envases de pl\u00e1stico y\/o tecnopor podr\u00edan originar c\u00e1ncer - %<\/title>\n<meta name=\"description\" content=\"Los envases de pl\u00e1stico y\/o tecnopor utilizados para servir o almacenar las comidas podr\u00edan originar c\u00e1ncer si es que se someten a altas temperaturas, de acuerdo a investigaciones a nivel mundial de los \u00faltimos 50 a\u00f1os.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/drmauricioleon.net\/portal\/2017\/04\/20\/envases-de-plastico-y-o-tecnopor-podrian-originar-cancer\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Envases de pl\u00e1stico y\/o tecnopor podr\u00edan originar c\u00e1ncer - %\" \/>\n<meta property=\"og:description\" content=\"Los envases de pl\u00e1stico y\/o tecnopor utilizados para servir o almacenar las comidas podr\u00edan originar c\u00e1ncer si es que se someten a altas temperaturas, de acuerdo a investigaciones a nivel mundial de los \u00faltimos 50 a\u00f1os.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/drmauricioleon.net\/portal\/2017\/04\/20\/envases-de-plastico-y-o-tecnopor-podrian-originar-cancer\/\" \/>\n<meta property=\"og:site_name\" content=\"Dr Mauricio Le\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Dr.mauricioleon\" \/>\n<meta property=\"article:published_time\" content=\"2017-04-20T19:52:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-06T19:56:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/drmauricioleon.net\/portal\/wp-content\/uploads\/2021\/09\/envases-de-plastico-.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1079\" \/>\n\t<meta property=\"og:image:height\" content=\"713\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@drleonmauricio\" \/>\n<meta name=\"twitter:site\" content=\"@drleonmauricio\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mauricio Le\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/drmauricioleon.net\/portal\/#organization\",\"name\":\"Dr. Mauricio Le\u00f3n\",\"url\":\"https:\/\/drmauricioleon.net\/portal\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/Dr.mauricioleon\",\"https:\/\/www.linkedin.com\/in\/mauricio-le\u00f3n-rivera-ab525598\",\"http:\/\/www.youtube.com\/user\/centrodetector\",\"https:\/\/twitter.com\/drleonmauricio\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/drmauricioleon.net\/portal\/#logo\",\"inLanguage\":\"es-PE\",\"url\":\"https:\/\/drmauricioleon.net\/portal\/wp-content\/uploads\/2020\/01\/logo-drml-e1586281768776.png\",\"contentUrl\":\"https:\/\/drmauricioleon.net\/portal\/wp-content\/uploads\/2020\/01\/logo-drml-e1586281768776.png\",\"width\":220,\"height\":72,\"caption\":\"Dr. Mauricio Le\u00f3n\"},\"image\":{\"@id\":\"https:\/\/drmauricioleon.net\/portal\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/drmauricioleon.net\/portal\/#website\",\"url\":\"https:\/\/drmauricioleon.net\/portal\/\",\"name\":\"Dr Mauricio Le\u00f3n\",\"description\":\"Cirujano general y onc\u00f3logo y sub especialista en tumores de Mamas, Tejidos Blandos y Piel. Es m\u00e9dico staff de la Cl\u00ednica Ricardo Palma y de Oncosalud.\",\"publisher\":{\"@id\":\"https:\/\/drmauricioleon.net\/portal\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/drmauricioleon.net\/portal\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-PE\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/drmauricioleon.net\/portal\/2017\/04\/20\/envases-de-plastico-y-o-tecnopor-podrian-originar-cancer\/#primaryimage\",\"inLanguage\":\"es-PE\",\"url\":\"https:\/\/drmauricioleon.net\/portal\/wp-content\/uploads\/2021\/09\/envases-de-plastico-.jpg\",\"contentUrl\":\"https:\/\/drmauricioleon.net\/portal\/wp-content\/uploads\/2021\/09\/envases-de-plastico-.jpg\",\"width\":1079,\"height\":713},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/drmauricioleon.net\/portal\/2017\/04\/20\/envases-de-plastico-y-o-tecnopor-podrian-originar-cancer\/#webpage\",\"url\":\"https:\/\/drmauricioleon.net\/portal\/2017\/04\/20\/envases-de-plastico-y-o-tecnopor-podrian-originar-cancer\/\",\"name\":\"Envases de pl\u00e1stico y\/o tecnopor podr\u00edan originar c\u00e1ncer - %\",\"isPartOf\":{\"@id\":\"https:\/\/drmauricioleon.net\/portal\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/drmauricioleon.net\/portal\/2017\/04\/20\/envases-de-plastico-y-o-tecnopor-podrian-originar-cancer\/#primaryimage\"},\"datePublished\":\"2017-04-20T19:52:00+00:00\",\"dateModified\":\"2021-09-06T19:56:24+00:00\",\"description\":\"Los envases de pl\u00e1stico y\/o tecnopor utilizados para servir o almacenar las comidas podr\u00edan originar c\u00e1ncer si es que se someten a altas temperaturas, de acuerdo a investigaciones a nivel mundial de los \u00faltimos 50 a\u00f1os.\",\"breadcrumb\":{\"@id\":\"https:\/\/drmauricioleon.net\/portal\/2017\/04\/20\/envases-de-plastico-y-o-tecnopor-podrian-originar-cancer\/#breadcrumb\"},\"inLanguage\":\"es-PE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/drmauricioleon.net\/portal\/2017\/04\/20\/envases-de-plastico-y-o-tecnopor-podrian-originar-cancer\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/drmauricioleon.net\/portal\/2017\/04\/20\/envases-de-plastico-y-o-tecnopor-podrian-originar-cancer\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/drmauricioleon.net\/portal\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Envases de pl\u00e1stico y\/o tecnopor podr\u00edan originar c\u00e1ncer\"}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/drmauricioleon.net\/portal\/2017\/04\/20\/envases-de-plastico-y-o-tecnopor-podrian-originar-cancer\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/drmauricioleon.net\/portal\/2017\/04\/20\/envases-de-plastico-y-o-tecnopor-podrian-originar-cancer\/#webpage\"},\"author\":{\"@id\":\"https:\/\/drmauricioleon.net\/portal\/#\/schema\/person\/b453c933295f6151407ceda3b9bf95a4\"},\"headline\":\"Envases de pl\u00e1stico y\/o tecnopor podr\u00edan originar c\u00e1ncer\",\"datePublished\":\"2017-04-20T19:52:00+00:00\",\"dateModified\":\"2021-09-06T19:56:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/drmauricioleon.net\/portal\/2017\/04\/20\/envases-de-plastico-y-o-tecnopor-podrian-originar-cancer\/#webpage\"},\"wordCount\":546,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/drmauricioleon.net\/portal\/#organization\"},\"image\":{\"@id\":\"https:\/\/drmauricioleon.net\/portal\/2017\/04\/20\/envases-de-plastico-y-o-tecnopor-podrian-originar-cancer\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/drmauricioleon.net\/portal\/wp-content\/uploads\/2021\/09\/envases-de-plastico-.jpg\",\"keywords\":[\"Envases de pl\u00e1stico\",\"riesgo de c\u00e1ncer\",\"tecnopor\"],\"articleSection\":[\"Informativo\"],\"inLanguage\":\"es-PE\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/drmauricioleon.net\/portal\/2017\/04\/20\/envases-de-plastico-y-o-tecnopor-podrian-originar-cancer\/#respond\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/drmauricioleon.net\/portal\/#\/schema\/person\/b453c933295f6151407ceda3b9bf95a4\",\"name\":\"Mauricio Le\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/drmauricioleon.net\/portal\/#personlogo\",\"inLanguage\":\"es-PE\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/430c938de37db4d449829c9260d5025f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/430c938de37db4d449829c9260d5025f?s=96&d=mm&r=g\",\"caption\":\"Mauricio Le\u00f3n\"},\"url\":\"https:\/\/drmauricioleon.net\/portal\/author\/bardales\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Envases de pl\u00e1stico y\/o tecnopor podr\u00edan originar c\u00e1ncer - %","description":"Los envases de pl\u00e1stico y\/o tecnopor utilizados para servir o almacenar las comidas podr\u00edan originar c\u00e1ncer si es que se someten a altas temperaturas, de acuerdo a investigaciones a nivel mundial de los \u00faltimos 50 a\u00f1os.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/drmauricioleon.net\/portal\/2017\/04\/20\/envases-de-plastico-y-o-tecnopor-podrian-originar-cancer\/","og_locale":"es_ES","og_type":"article","og_title":"Envases de pl\u00e1stico y\/o tecnopor podr\u00edan originar c\u00e1ncer - %","og_description":"Los envases de pl\u00e1stico y\/o tecnopor utilizados para servir o almacenar las comidas podr\u00edan originar c\u00e1ncer si es que se someten a altas temperaturas, de acuerdo a investigaciones a nivel mundial de los \u00faltimos 50 a\u00f1os.","og_url":"https:\/\/drmauricioleon.net\/portal\/2017\/04\/20\/envases-de-plastico-y-o-tecnopor-podrian-originar-cancer\/","og_site_name":"Dr Mauricio Le\u00f3n","article_publisher":"https:\/\/www.facebook.com\/Dr.mauricioleon","article_published_time":"2017-04-20T19:52:00+00:00","article_modified_time":"2021-09-06T19:56:24+00:00","og_image":[{"width":1079,"height":713,"url":"https:\/\/drmauricioleon.net\/portal\/wp-content\/uploads\/2021\/09\/envases-de-plastico-.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_creator":"@drleonmauricio","twitter_site":"@drleonmauricio","twitter_misc":{"Written by":"Mauricio Le\u00f3n","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/drmauricioleon.net\/portal\/#organization","name":"Dr. Mauricio Le\u00f3n","url":"https:\/\/drmauricioleon.net\/portal\/","sameAs":["https:\/\/www.facebook.com\/Dr.mauricioleon","https:\/\/www.linkedin.com\/in\/mauricio-le\u00f3n-rivera-ab525598","http:\/\/www.youtube.com\/user\/centrodetector","https:\/\/twitter.com\/drleonmauricio"],"logo":{"@type":"ImageObject","@id":"https:\/\/drmauricioleon.net\/portal\/#logo","inLanguage":"es-PE","url":"https:\/\/drmauricioleon.net\/portal\/wp-content\/uploads\/2020\/01\/logo-drml-e1586281768776.png","contentUrl":"https:\/\/drmauricioleon.net\/portal\/wp-content\/uploads\/2020\/01\/logo-drml-e1586281768776.png","width":220,"height":72,"caption":"Dr. Mauricio Le\u00f3n"},"image":{"@id":"https:\/\/drmauricioleon.net\/portal\/#logo"}},{"@type":"WebSite","@id":"https:\/\/drmauricioleon.net\/portal\/#website","url":"https:\/\/drmauricioleon.net\/portal\/","name":"Dr Mauricio Le\u00f3n","description":"Cirujano general y onc\u00f3logo y sub especialista en tumores de Mamas, Tejidos Blandos y Piel. Es m\u00e9dico staff de la Cl\u00ednica Ricardo Palma y de Oncosalud.","publisher":{"@id":"https:\/\/drmauricioleon.net\/portal\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/drmauricioleon.net\/portal\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-PE"},{"@type":"ImageObject","@id":"https:\/\/drmauricioleon.net\/portal\/2017\/04\/20\/envases-de-plastico-y-o-tecnopor-podrian-originar-cancer\/#primaryimage","inLanguage":"es-PE","url":"https:\/\/drmauricioleon.net\/portal\/wp-content\/uploads\/2021\/09\/envases-de-plastico-.jpg","contentUrl":"https:\/\/drmauricioleon.net\/portal\/wp-content\/uploads\/2021\/09\/envases-de-plastico-.jpg","width":1079,"height":713},{"@type":"WebPage","@id":"https:\/\/drmauricioleon.net\/portal\/2017\/04\/20\/envases-de-plastico-y-o-tecnopor-podrian-originar-cancer\/#webpage","url":"https:\/\/drmauricioleon.net\/portal\/2017\/04\/20\/envases-de-plastico-y-o-tecnopor-podrian-originar-cancer\/","name":"Envases de pl\u00e1stico y\/o tecnopor podr\u00edan originar c\u00e1ncer - %","isPartOf":{"@id":"https:\/\/drmauricioleon.net\/portal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/drmauricioleon.net\/portal\/2017\/04\/20\/envases-de-plastico-y-o-tecnopor-podrian-originar-cancer\/#primaryimage"},"datePublished":"2017-04-20T19:52:00+00:00","dateModified":"2021-09-06T19:56:24+00:00","description":"Los envases de pl\u00e1stico y\/o tecnopor utilizados para servir o almacenar las comidas podr\u00edan originar c\u00e1ncer si es que se someten a altas temperaturas, de acuerdo a investigaciones a nivel mundial de los \u00faltimos 50 a\u00f1os.","breadcrumb":{"@id":"https:\/\/drmauricioleon.net\/portal\/2017\/04\/20\/envases-de-plastico-y-o-tecnopor-podrian-originar-cancer\/#breadcrumb"},"inLanguage":"es-PE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/drmauricioleon.net\/portal\/2017\/04\/20\/envases-de-plastico-y-o-tecnopor-podrian-originar-cancer\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/drmauricioleon.net\/portal\/2017\/04\/20\/envases-de-plastico-y-o-tecnopor-podrian-originar-cancer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/drmauricioleon.net\/portal\/"},{"@type":"ListItem","position":2,"name":"Envases de pl\u00e1stico y\/o tecnopor podr\u00edan originar c\u00e1ncer"}]},{"@type":"Article","@id":"https:\/\/drmauricioleon.net\/portal\/2017\/04\/20\/envases-de-plastico-y-o-tecnopor-podrian-originar-cancer\/#article","isPartOf":{"@id":"https:\/\/drmauricioleon.net\/portal\/2017\/04\/20\/envases-de-plastico-y-o-tecnopor-podrian-originar-cancer\/#webpage"},"author":{"@id":"https:\/\/drmauricioleon.net\/portal\/#\/schema\/person\/b453c933295f6151407ceda3b9bf95a4"},"headline":"Envases de pl\u00e1stico y\/o tecnopor podr\u00edan originar c\u00e1ncer","datePublished":"2017-04-20T19:52:00+00:00","dateModified":"2021-09-06T19:56:24+00:00","mainEntityOfPage":{"@id":"https:\/\/drmauricioleon.net\/portal\/2017\/04\/20\/envases-de-plastico-y-o-tecnopor-podrian-originar-cancer\/#webpage"},"wordCount":546,"commentCount":0,"publisher":{"@id":"https:\/\/drmauricioleon.net\/portal\/#organization"},"image":{"@id":"https:\/\/drmauricioleon.net\/portal\/2017\/04\/20\/envases-de-plastico-y-o-tecnopor-podrian-originar-cancer\/#primaryimage"},"thumbnailUrl":"https:\/\/drmauricioleon.net\/portal\/wp-content\/uploads\/2021\/09\/envases-de-plastico-.jpg","keywords":["Envases de pl\u00e1stico","riesgo de c\u00e1ncer","tecnopor"],"articleSection":["Informativo"],"inLanguage":"es-PE","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/drmauricioleon.net\/portal\/2017\/04\/20\/envases-de-plastico-y-o-tecnopor-podrian-originar-cancer\/#respond"]}]},{"@type":"Person","@id":"https:\/\/drmauricioleon.net\/portal\/#\/schema\/person\/b453c933295f6151407ceda3b9bf95a4","name":"Mauricio Le\u00f3n","image":{"@type":"ImageObject","@id":"https:\/\/drmauricioleon.net\/portal\/#personlogo","inLanguage":"es-PE","url":"https:\/\/secure.gravatar.com\/avatar\/430c938de37db4d449829c9260d5025f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/430c938de37db4d449829c9260d5025f?s=96&d=mm&r=g","caption":"Mauricio Le\u00f3n"},"url":"https:\/\/drmauricioleon.net\/portal\/author\/bardales\/"}]}},"_links":{"self":[{"href":"https:\/\/drmauricioleon.net\/portal\/wp-json\/wp\/v2\/posts\/4060"}],"collection":[{"href":"https:\/\/drmauricioleon.net\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/drmauricioleon.net\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/drmauricioleon.net\/portal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/drmauricioleon.net\/portal\/wp-json\/wp\/v2\/comments?post=4060"}],"version-history":[{"count":1,"href":"https:\/\/drmauricioleon.net\/portal\/wp-json\/wp\/v2\/posts\/4060\/revisions"}],"predecessor-version":[{"id":4062,"href":"https:\/\/drmauricioleon.net\/portal\/wp-json\/wp\/v2\/posts\/4060\/revisions\/4062"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/drmauricioleon.net\/portal\/wp-json\/wp\/v2\/media\/4061"}],"wp:attachment":[{"href":"https:\/\/drmauricioleon.net\/portal\/wp-json\/wp\/v2\/media?parent=4060"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/drmauricioleon.net\/portal\/wp-json\/wp\/v2\/categories?post=4060"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/drmauricioleon.net\/portal\/wp-json\/wp\/v2\/tags?post=4060"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}